{"id":57768,"date":"2021-04-21T11:23:54","date_gmt":"2021-04-21T08:23:54","guid":{"rendered":"https:\/\/artlink.ee\/product\/trendline-mahogany-40x50\/"},"modified":"2022-02-19T01:10:59","modified_gmt":"2022-02-18T23:10:59","slug":"trendline-mahogany-40x50","status":"publish","type":"product","link":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/","title":{"rendered":"Trendline Mahogany 40&#215;50"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":121615,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3447],"product_tag":[],"class_list":{"0":"post-57768","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bilderrahmen","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trendline Mahogany 40x50 - Artlink<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trendline Mahogany 40x50 - Artlink\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/\" \/>\n<meta property=\"og:site_name\" content=\"Artlink\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-18T23:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/\",\"url\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/\",\"name\":\"Trendline Mahogany 40x50 - Artlink\",\"isPartOf\":{\"@id\":\"https:\/\/artlink.ee\/da\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg\",\"datePublished\":\"2021-04-21T08:23:54+00:00\",\"dateModified\":\"2022-02-18T23:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#primaryimage\",\"url\":\"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg\",\"contentUrl\":\"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg\",\"width\":640,\"height\":348},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/artlink.ee\/da\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkter\",\"item\":\"https:\/\/artlink.ee\/da\/produkter\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trendline Mahogany 40&#215;50\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artlink.ee\/da\/#website\",\"url\":\"https:\/\/artlink.ee\/da\/\",\"name\":\"Artlink\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/artlink.ee\/da\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trendline Mahogany 40x50 - Artlink","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/","og_locale":"da_DK","og_type":"article","og_title":"Trendline Mahogany 40x50 - Artlink","og_url":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/","og_site_name":"Artlink","article_modified_time":"2022-02-18T23:10:59+00:00","og_image":[{"width":640,"height":348,"url":"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/","url":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/","name":"Trendline Mahogany 40x50 - Artlink","isPartOf":{"@id":"https:\/\/artlink.ee\/da\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#primaryimage"},"image":{"@id":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#primaryimage"},"thumbnailUrl":"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg","datePublished":"2021-04-21T08:23:54+00:00","dateModified":"2022-02-18T23:10:59+00:00","breadcrumb":{"@id":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/"]}]},{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#primaryimage","url":"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg","contentUrl":"https:\/\/artlink.ee\/wp-content\/uploads\/2021\/07\/18134-Trendline-Dark-Mahogany.jpg","width":640,"height":348},{"@type":"BreadcrumbList","@id":"https:\/\/artlink.ee\/da\/vare\/trendline-mahogany-40x50\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/artlink.ee\/da\/"},{"@type":"ListItem","position":2,"name":"Produkter","item":"https:\/\/artlink.ee\/da\/produkter\/"},{"@type":"ListItem","position":3,"name":"Trendline Mahogany 40&#215;50"}]},{"@type":"WebSite","@id":"https:\/\/artlink.ee\/da\/#website","url":"https:\/\/artlink.ee\/da\/","name":"Artlink","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artlink.ee\/da\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"}]}},"_links":{"self":[{"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/product\/57768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/media\/121615"}],"wp:attachment":[{"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/media?parent=57768"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/product_brand?post=57768"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/product_cat?post=57768"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artlink.ee\/da\/wp-json\/wp\/v2\/product_tag?post=57768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}